{"id":25008,"date":"2025-10-27T15:45:25","date_gmt":"2025-10-27T07:45:25","guid":{"rendered":"https:\/\/us.felicitysolar.store\/?post_type=product&#038;p=25008"},"modified":"2026-04-08T09:17:44","modified_gmt":"2026-04-08T01:17:44","slug":"p2-80w","status":"publish","type":"product","link":"https:\/\/felicitysolar.ca\/fr\/produit\/p2-80w\/","title":{"rendered":"P2-80W"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"25008\" class=\"elementor elementor-25008\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83b15b8 e-flex e-con-boxed e-con e-parent\" data-id=\"83b15b8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-624ed84b e-con-full e-flex e-con e-child\" data-id=\"624ed84b\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2acbec46 elementor-absolute elementor-widget elementor-widget-ucaddon_sideways_vertical_text\" data-id=\"2acbec46\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"ucaddon_sideways_vertical_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Sideways Vertical Text -->\n<style>\/* widget: Sideways Vertical Text *\/\n\n#uc_sideways_vertical_text_elementor_2acbec46\n{\n  writing-mode: vertical-rl;\n  text-orientation: mixed;\n  color:#FFFFFF14;\n  text-decoration:none;\n  display:flex;\n  justify-content:center;\n  align-items:center;\n  white-space: nowrap;\n  \n  \n\ttransform: rotate(180deg);  \n\t\n\n  \n}\n\n<\/style>\n\n\t\n<div id=\"uc_sideways_vertical_text_elementor_2acbec46\" class=\"sideways_vertical_text\">\n\n  \n\n\n    P2 Series\n  \n\n  \n  \n<\/div>\n      \n\n<!-- end Sideways Vertical Text -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-458e5303 elementor-widget elementor-widget-image\" data-id=\"458e5303\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/P2-80W-1.webp\" class=\"attachment-large size-large wp-image-25011\" alt=\"P2 80w 1.webp\" srcset=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/P2-80W-1.webp 800w, https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/P2-80W-1-300x300.webp 300w, https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/P2-80W-1-150x150.webp 150w, https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/P2-80W-1-768x768.webp 768w, https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/P2-80W-1-600x600.webp 600w, https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/P2-80W-1-100x100.webp 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5d1d00 e-con-full e-flex e-con e-child\" data-id=\"e5d1d00\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ea6bbf elementor-widget-tablet__width-initial elementor-widget elementor-widget-ucaddon_dual_color_heading\" data-id=\"5ea6bbf\" data-element_type=\"widget\" data-widget_type=\"ucaddon_dual_color_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Dual Color Heading -->\n\n<div class=\"ue-dual-color-heading\">\n  <h3>\n    <span class=\"ue-title-one\">P2<\/span> <span class=\"ue-title-two\">-80W<\/span>\n  <\/h3>\n<\/div>\n<!-- end Dual Color Heading -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3895dc elementor-widget elementor-widget-woocommerce-breadcrumb\" data-id=\"5f3895dc\" data-element_type=\"widget\" data-widget_type=\"woocommerce-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"woocommerce-breadcrumb\" aria-label=\"Breadcrumb\">Accueil<\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-537e34e0 e-con-full e-flex e-con e-child\" data-id=\"537e34e0\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13fe7f6e elementor-widget__width-auto e-transform ha-has-bg-overlay elementor-widget elementor-widget-heading\" data-id=\"13fe7f6e\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-9,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-4,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_widescreen&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_widescreen&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">80W (Mono)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea139bf elementor-widget__width-auto e-transform ha-has-bg-overlay elementor-widget elementor-widget-heading\" data-id=\"ea139bf\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-9,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-4,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_widescreen&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_widescreen&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Built-in 400WH<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16f17195 e-con-full e-flex e-con e-child\" data-id=\"16f17195\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61ba3ab0 elementor-widget__width-auto e-transform ha-has-bg-overlay elementor-widget elementor-widget-heading\" data-id=\"61ba3ab0\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-9,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-4,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_widescreen&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_widescreen&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">8H strong sunlight charge time<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b28134f elementor-widget__width-auto e-transform ha-has-bg-overlay elementor-widget elementor-widget-heading\" data-id=\"2b28134f\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-9,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-4,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_widescreen&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_widescreen&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">IP65 Ingress Protection<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72f57112 elementor-widget elementor-widget-ucaddon_card_carousel\" data-id=\"72f57112\" data-element_type=\"widget\" data-widget_type=\"ucaddon_card_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Card Carousel -->\n\t\t<link id='font-awesome-css' href='https:\/\/felicitysolar.ca\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/felicitysolar.ca\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='owl-carousel-css' href='https:\/\/felicitysolar.ca\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/owl-carousel-new\/assets\/owl.carousel.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='uc_ac_assets_file_animate_css_77907-css' href='https:\/\/felicitysolar.ca\/wp-content\/uploads\/ac_assets\/uc_classic_carousel\/animate.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Card Carousel *\/\n\n#uc_card_carousel_elementor_72f57112-wrapper{\n  min-height:1px;\n}\n\n#uc_card_carousel_elementor_72f57112 *{\n\t-webkit-box-sizing: border-box;\n\t-moz-box-sizing: border-box;\n\tbox-sizing: border-box;\n}\n\n#uc_card_carousel_elementor_72f57112 .ue-carousel-item{\n  overflow:hidden;\n  transition:0.3s;\n}\n\n#uc_card_carousel_elementor_72f57112 .uc_classic_carousel_container_holder{\n\tdisplay:block;\n\tposition:relative;\n\twidth:100%;\n    box-sizing: border-box;\n}\n#uc_card_carousel_elementor_72f57112 .uc_classic_carousel_placeholder{\n   position:relative;\n}\n\n\n#uc_card_carousel_elementor_72f57112 .uc_classic_carousel_placeholder img, #uc_card_carousel_elementor_72f57112 .ue_card_carousel_image_overlay{\n  transition: all 300ms;\n}\n\n.card_carousel_title{\n\tfont-size:21px;\n}\n\n.uc_classic_carousel .uc_classic_carousel_border{\n\tdisplay:block;\n    margin:0 auto;\n}\n\n.uc_classic_carousel  .uc_classic_carousel_placeholder img{\n\twidth:100%;    \n    display:block;\n}\n\n.uc_classic_carousel .uc_classic_carousel_content{\n  display: flex;\n  flex-flow: column nowrap;\n}\n\n.uc_classic_carousel .ue_button{\n  margin-top:auto;\n}\n\n.uc_classic_carousel .uc_classic_carousel_content .uc_more_btn {\n\tdisplay:inline-block;\n\ttext-decoration:none;\n\ttransition: all 0.5s ease;\n}\n\n#uc_card_carousel_elementor_72f57112 .owl-dots {\n  overflow:hidden;\n  text-align:center;\n}\n\n#uc_card_carousel_elementor_72f57112 .owl-dot {\n  border-radius:50%;\n  display:inline-block;\n}\n\n#uc_card_carousel_elementor_72f57112 .owl-nav .owl-prev,\n#uc_card_carousel_elementor_72f57112 .owl-nav .owl-next{\n    position:absolute;\n    display:flex;\n  \tjustify-content: center;\n  \talign-items: center;\n    text-align:center;\n}\n\n#uc_card_carousel_elementor_72f57112 .owl-nav .disabled{\n    display: none;  \n}\n\n\n#uc_card_carousel_elementor_72f57112 .ue-item-icon{\n  line-height:1em;\n  display:inline-flex;\n  justify-content:center;\n  align-items:center;  \n}\n\n#uc_card_carousel_elementor_72f57112 .ue-item-icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_card_carousel_elementor_72f57112 .ue-item-icon-wrapper{\n  display:flex;\n}\n\n#uc_card_carousel_elementor_72f57112 .uc_classic_carousel_container_holder {\n\t max-width: ;\n}\n\n\n\n@media screen and (max-width: 1024px) {\n  #uc_card_carousel_elementor_72f57112 .uc_classic_carousel_container_holder {\n\t max-width: ;\n  }\n}\n\n@media screen and (max-width: 767px) {\n  #uc_card_carousel_elementor_72f57112 .uc_classic_carousel_container_holder {\n    max-width: ;\n  }\n}\n\n<\/style>\n\n<div class=\"uc_classic_carousel\" id=\"uc_card_carousel_elementor_72f57112-wrapper\">\n        <div class=\"uc_carousel owl-carousel uc-items-wrapper  uc-remote-parent \" id=\"uc_card_carousel_elementor_72f57112\"  data-remoteid='auto' data-widgetname='Card Carousel' data-sync='true' data-syncid='group1' >\n          \t\n\n\n\n<div id=\"uc_card_carousel_elementor_72f57112_item1\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-2699ad8\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n        \n    \n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\">Product Introduction<\/div>\n        <div class=\"card_carousel_text\">1.1 Integrated design and source, high capacity LiFePO4 lithium battery, high energy, and long life, light weights, green and environmental protection, do not produce any harmful substances.<br>\n1.2 LED chip with high light efficiency which can reach 180LM\/W, and whole lamp light efficiency can reach 160LM\/W at least.<br>\n1.3 All series use intelligent controller which can increase 15%-30% charge efficiency.<br>\n1.4 Design with high efficiency solar cell (>22%).<br>\n1.5 Convenient installation and maintenance, no need of cable installation or special light pole, functional components modular design, installation and maintenance, convenient and quick replacement.<\/div>      \t\n\n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n\n\n\n<div id=\"uc_card_carousel_elementor_72f57112_item2\" class=\"uc_classic_carousel_container_holder ue-item elementor-repeater-item-9d05be0\" data-hide-item=\"false\">  \n  <div class=\"ue-carousel-item\">\n    \n        \n    \n    \n    <div class=\"uc_classic_carousel_content\" style=\"direction:ltr;\">    \n\n      \n          <div  class=\"card_carousel_title\">Product Advantages<\/div>\n        <div class=\"card_carousel_text\">Our solar lighting series combines efficiency, durability, and ease of use, making it an ideal choice for outdoor lighting in various environments.<br>\n- Long-life lithium battery for lasting durability<br>\n- Built-in MPPT controller for optimal solar charging<br>\n- \u226522% solar panel efficiency for maximum energy output<br>\n- Easy installation with minimal setup time<br>\n- IP65-rated for street light series and IP66-rated for flood light series<\/div>      \t\n\n      \t\n      \n    <\/div>\n    \n  <\/div>\n<\/div>\n\n      <\/div>\n<\/div>\n<!-- end Card Carousel -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38e7560 elementor-widget elementor-widget-ucaddon_neon_glowing_button_effect\" data-id=\"38e7560\" data-element_type=\"widget\" data-widget_type=\"ucaddon_neon_glowing_button_effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Neon Glowing Button Effect -->\n\n<style>\/* widget: Neon Glowing Button Effect *\/\n\n#uc_neon_glowing_button_effect_elementor_38e7560{\n  position: relative;\n  z-index:1;\n}\n#uc_neon_glowing_button_effect_elementor_38e7560 *{\n    margin: 0;\n}\n#uc_neon_glowing_button_effect_elementor_38e7560.ue_neon_btn_wrapper{\n  display: flex;\n  justify-content: center;\n  align-items: center;\n  gap:50px;\n}\n#uc_neon_glowing_button_effect_elementor_38e7560 .ue_neon_btn {\n  display: flex;\n  flex-direction:row;\n  justify-content: center;\n  align-items: center;\n  position: relative;\n  border-radius: 100px;\n  overflow:visible;\n  transition: 0.5s;\n}\n\n#uc_neon_glowing_button_effect_elementor_38e7560 .ue_neon_btn:after {\n  content: '';\n  position: absolute;\n  box-sizing:content-box;\n  border-radius: calc(100px + 2px);\n  width: 100%;\n  height: 100%;\n  translate: -50% -50%;\n  left: 50%;\n  top: 50%;\n  z-index: -1;\n  animation: rotateuc_neon_glowing_button_effect_elementor_38e7560 2000ms linear infinite;\n  padding: 2px;\n  --angle: 0deg;\n  filter: ;\n  background: conic-gradient(from var(--angle) ,\n          #ff003700 50deg,\n      #FF8A33 360deg\n          );\n  transition: all 0.5s;\n}\n\n#uc_neon_glowing_button_effect_elementor_38e7560 .ue_neon_btn:before {\n  content: '';\n  position: absolute;\n  box-sizing:content-box;\n  border-radius: 100px;\n  width: 100%;\n  height: 100%;\n  translate: -50% -50%;\n  left: 50%;\n  top: 50%;\n  z-index: -2;\n  transition: all 0.5s;\n  animation: rotateuc_neon_glowing_button_effect_elementor_38e7560 2000ms linear infinite;\n  filter: blur(20px) brightness(1)  ;\n    -webkit-backface-visibility: hidden;\n-moz-backface-visibility: hidden;\n  -webkit-transform: translate3d(0, 0, 0);\n-moz-transform: translate3d(0, 0, 0);\n  background: conic-gradient(from var(--angle),\n          #ff003700 50deg,\n      #FF8A33 360deg\n          );\n}\n\n\n@property --angle {\n  syntax: '<angle>';\n  initial-value: 0deg;\n  inherits: false;\n}\n@property --hueuc_neon_glowing_button_effect_elementor_38e7560 {\n  syntax: '<angle>';\n  initial-value: 0deg;\n  inherits: false;\n}\n@keyframes rotateuc_neon_glowing_button_effect_elementor_38e7560 {\n  0% {\n    --angle: 0deg;\n       }\n  50% { \n      }\n  100% { \n    --angle: 360deg;\n      }\n}\n\n\/* hover *\/\n#uc_neon_glowing_button_effect_elementor_38e7560 .ue_neon_btn:hover:before,\n#uc_neon_glowing_button_effect_elementor_38e7560 .ue_neon_btn:hover:after{\n  transition: all 0.5s;\n  animation-play-state: paused;\n  background: conic-gradient(from var(--angle),\n          #FF8A33 0deg,\n      #FF8A33 360deg\n          );\n}\n\n#uc_neon_glowing_button_effect_elementor_38e7560 .ue-btn svg\n{\n  height:1em;\n  width:1em;\n}\n\n<\/style>\n\n<div id=\"uc_neon_glowing_button_effect_elementor_38e7560\" class=\"ue_neon_btn_wrapper \">\n  <a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE0NzQxIiwidG9nZ2xlIjpmYWxzZX0%3D\"  class=\"ue_neon_btn\">\n    <div class=\"ue-btn-icon\"><i class='fas fa-phone'><\/i><\/div>    Contact Us\n      <\/a>\n<\/div>\n<!-- end Neon Glowing Button Effect -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3da42708 e-con-full e-flex e-con e-parent\" data-id=\"3da42708\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t<div class=\"elementor-element elementor-element-32ab3793 e-flex e-con-boxed e-con e-child\" data-id=\"32ab3793\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-57510813 e-flex e-con-boxed e-con e-child\" data-id=\"57510813\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75894d9e elementor-pagination-position-inside elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"75894d9e\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u56fe\u50cf\u8f6e\u64ad\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/P2-80W-2.webp\" alt=\"P2 80w 2.webp\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 2\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/P2-80W-1.webp\" alt=\"P2 80w 1.webp\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-361eaf32 e-flex e-con-boxed e-con e-child\" data-id=\"361eaf32\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4625b15e e-flex e-con-boxed e-con e-child\" data-id=\"4625b15e\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1d066f2b e-flex e-con-boxed e-con e-child\" data-id=\"1d066f2b\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ad946e2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"3ad946e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Model<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2732c0d9 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2732c0d9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">P2-80W<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17047b13 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"17047b13\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-468d30df e-flex e-con-boxed e-con e-child\" data-id=\"468d30df\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f549498 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"3f549498\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Solar Module<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45824f9a elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"45824f9a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">80W (Mono)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-576512b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"576512b\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b9f400 e-flex e-con-boxed e-con e-child\" data-id=\"7b9f400\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43c3ad20 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"43c3ad20\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">High capacity lithium battery<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-549a574b elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"549a574b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Built-in 400WH<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a844ecb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2a844ecb\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-304892a4 e-con-full e-flex e-con e-child\" data-id=\"304892a4\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-130b3b4a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"130b3b4a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Solar panel charge time<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7573382b elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7573382b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">8H strong sunlight<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fc90bfd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1fc90bfd\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72766587 e-flex e-con-boxed e-con e-child\" data-id=\"72766587\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6af66aa5 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"6af66aa5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Working Time All light pattern<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c90fc9b elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2c90fc9b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u2265 12 hours<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ae097fd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1ae097fd\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23904128 e-flex e-con-boxed e-con e-child\" data-id=\"23904128\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-541468bd elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"541468bd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Raining days backup<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9a57fd elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5f9a57fd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">3 days<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e6f05d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7e6f05d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75d1c8e3 e-con-full e-flex e-con e-child\" data-id=\"75d1c8e3\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-861139c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"861139c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Light pole diameter<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27a8c15b elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"27a8c15b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">60mm<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d50968 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5d50968\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a4aa1d8 e-con-full e-flex e-con e-child\" data-id=\"6a4aa1d8\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23e3c7ca elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"23e3c7ca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Storage temperature<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3151bb2f elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3151bb2f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">0-55\u2103<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12d33a62 e-flex e-con-boxed e-con e-parent\" data-id=\"12d33a62\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3271c8d5 e-con-full e-flex e-con e-child\" data-id=\"3271c8d5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55e61681 elementor-widget elementor-widget-heading\" data-id=\"55e61681\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Download<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16e9c00e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"16e9c00e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a3f2f86 e-con-full e-flex e-con e-child\" data-id=\"5a3f2f86\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-45246f1 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"45246f1\" data-element_type=\"widget\" data-settings=\"{&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"72500977\" aria-label=\"Tabs. Open items with Enter or Space, close with Escape and navigate using the Arrow keys.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-725009771\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-725009771\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tUser Guide\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-725009772\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-725009772\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tDatasheet\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-725009771\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-725009771\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-267c02ef e-con-full e-flex e-con e-child\" data-id=\"267c02ef\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-219bdb18 elementor-list-item-link-inline elementor-align-left elementor-widget__width-initial e-transform elementor-widget elementor-widget-icon-list\" data-id=\"219bdb18\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/doc.felicitysolar.com\/manual\/Street-Light\/P2\/P2-40W%20P2-60W%20P2-80W%20Street%20Lamp%20User%20Guide%20-%20EN.pdf\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cloud-download-alt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M537.6 226.6c4.1-10.7 6.4-22.4 6.4-34.6 0-53-43-96-96-96-19.7 0-38.1 6-53.3 16.2C367 64.2 315.3 32 256 32c-88.4 0-160 71.6-160 160 0 2.7.1 5.4.2 8.1C40.2 219.8 0 273.2 0 336c0 79.5 64.5 144 144 144h368c70.7 0 128-57.3 128-128 0-61.9-44-113.6-102.4-125.4zm-132.9 88.7L299.3 420.7c-6.2 6.2-16.4 6.2-22.6 0L171.3 315.3c-10.1-10.1-2.9-27.3 11.3-27.3H248V176c0-8.8 7.2-16 16-16h48c8.8 0 16 7.2 16 16v112h65.4c14.2 0 21.4 17.2 11.3 27.3z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">P2-40W P2-60W P2-80W User Guide - EN<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-725009772\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-725009772\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-283c581f e-con-full e-flex e-con e-child\" data-id=\"283c581f\" data-element_type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2da088ac elementor-list-item-link-inline elementor-align-left elementor-widget__width-initial e-transform elementor-widget elementor-widget-icon-list\" data-id=\"2da088ac\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_scale_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/doc.felicitysolar.com\/Datasheet\/Street-light-en\/P2-60W%20p2-80W%20Datasheet%20-%20EN.pdf\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cloud-download-alt\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M537.6 226.6c4.1-10.7 6.4-22.4 6.4-34.6 0-53-43-96-96-96-19.7 0-38.1 6-53.3 16.2C367 64.2 315.3 32 256 32c-88.4 0-160 71.6-160 160 0 2.7.1 5.4.2 8.1C40.2 219.8 0 273.2 0 336c0 79.5 64.5 144 144 144h368c70.7 0 128-57.3 128-128 0-61.9-44-113.6-102.4-125.4zm-132.9 88.7L299.3 420.7c-6.2 6.2-16.4 6.2-22.6 0L171.3 315.3c-10.1-10.1-2.9-27.3 11.3-27.3H248V176c0-8.8 7.2-16 16-16h48c8.8 0 16 7.2 16 16v112h65.4c14.2 0 21.4 17.2 11.3 27.3z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">P2-60W P2-80W Datasheet - EN<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-658906e5 e-flex e-con-boxed e-con e-parent\" data-id=\"658906e5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-457e817a elementor-widget elementor-widget-ucaddon_woocommerce_product_carousel\" data-id=\"457e817a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_woocommerce_product_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Woo Product Carousel -->\n\n<style>\/* widget: Woo Product Carousel *\/\n\n#uc_woocommerce_product_carousel_elementor_457e817a{\n  min-height:1px;\n  position:relative;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a *{\n  box-sizing:border-box;\n}\n\n\n#uc_woocommerce_product_carousel_elementor_457e817a .ue_woocommerce_product_label-custom-field{\n\tz-index: 100;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_image_carousel_content{ \n  box-sizing:border-box;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_image_carousel_placeholder{\n  overflow:hidden;\n  position:relative;\n}\n\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_more_btn-custom-field{\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .owl-nav .owl-prev{\n    position:absolute;\n    display:inline-block;\n    text-align:center;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .owl-nav .owl-next{\n  position:absolute;\n  display:inline-block;\n  text-align:center;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_image_carousel_container_holder{\n  text-align:center;\n  overflow:hidden;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_btn, \n#uc_woocommerce_product_carousel_elementor_457e817a .uc-button-addcart, \n#uc_woocommerce_product_carousel_elementor_457e817a .added_to_cart,\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_more_btn-custom-field{\n  display:block;\n  text-decoration:none;\n  text-align:center;\n  transition: all 0.25s ease-in-out;\n}\n\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_product_image--second{\n  \twidth: 100%;\n    height: 100%;\n    object-fit: cover;\n\tposition: absolute;\n  \ttop: 0;\n  \tright: 0;\n  \t  \t\t  \t\t\ttransform: translate(-100%, 0);\n  \t\t    \n  \t \n  \ttransition: all .3s;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_image_carousel_placeholder:hover .uc_product_image--second{  \n  \t\t\ttransform: translate(0, 0);\n  \t}\n\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_product_image img{\n  width:100%;\n  font-size:0px;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .owl-dots {\n  overflow:hidden;\n  display:block !important;\n  text-align:center;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .owl-dot {\n  border-radius:50%;\n  display:inline-block;\n}\n\n\n\n\n\n\n\n.uc-button-addcart.added{\n  display:none !important;\n}\n.uc_post_title{\n  font-size:21px;\n}\n.uc_overlay_image_carousel{\n  min-height:1px;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_prices > div{\n  display:block;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_image_carousel_container_holder .uc_product_image{\n  transition:0.5s;\n}\n\n\n\n#uc_woocommerce_product_carousel_elementor_457e817a .ue_woocommerce_product_carousel_sale_label{\n  display:inline-flex;\n  position:absolute;\n  left:10px;\n  top:10px;\n  align-items:center;\n  justify-content:center;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .ue_woocommerce_product_grid_out_of_stock_label{\n    position: absolute;\n  \tdisplay:inline-flex;\n    align-items:center;\n    justify-content:center;\n  \tleft:10px;\n  \ttop:10px;\n  \tz-index: 1;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_image_carousel_content_inside{\n  display:flex;\n  flex-direction:column;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_buttons{\n  margin-top:auto;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .ue-woo-item{\n  transition:0.3s;\n}\n\n\n\n#uc_woocommerce_product_carousel_elementor_457e817a .jet-wishlist-button__container{\n  \tmargin-top:10px;\n}\n\n\/* hide default arrows in input type number *\/\n\/* Chrome, Safari, Edge, Opera *\/\n#uc_woocommerce_product_carousel_elementor_457e817a input.uc_carousel-count-buttons__number::-webkit-outer-spin-button,\n#uc_woocommerce_product_carousel_elementor_457e817a input.uc_carousel-count-buttons__number::-webkit-inner-spin-button{\n\t-webkit-appearance: none;\n  \tmargin: 0;\n}\n\n\/* Firefox *\/\n#uc_woocommerce_product_carousel_elementor_457e817a input.uc_carousel-count-buttons__number[type=number]{\n\t-moz-appearance: textfield;\n}\n\/* end hide default arrows in input type number *\/\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_carousel-count-buttons{\n\tdisplay: inline-flex;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_carousel-count-buttons button{\n\tdisplay: flex;\n    align-items:center;\n    justify-content:center;\n    flex-grow:0;\n    flex-shrink:0;\n    line-height:1em;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_carousel-count-buttons button:disabled{\n\topacity:0.5;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_carousel-count-buttons button svg{\n\theight:1em;\n    width:1em;\n}\n\n#uc_woocommerce_product_carousel_elementor_457e817a input.uc_carousel-count-buttons__number{\n  text-align:center;\n  flex-grow:1;\n}\n\n\t#uc_woocommerce_product_carousel_elementor_457e817a .owl-stage\n        {\n            transition-timing-function: linear!important;\n        }\n\n\n#uc_woocommerce_product_carousel_elementor_457e817a .owl-stage{\n   display: flex;\n}\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_image_carousel_container_holder{\n    display: flex;\n    align-items: stretch;\n    flex-direction: column;\n}\n#uc_woocommerce_product_carousel_elementor_457e817a .uc_image_carousel_content{\n    display: flex;\n    flex-direction: column;\n    flex: 1;\n}\n#uc_woocommerce_product_carousel_elementor_457e817a .owl-item {\n    align-items: stretch;\n    display: flex;\n}\n\n\n#uc_woocommerce_product_carousel_elementor_457e817a .owl-nav .owl-prev.disabled,\n#uc_woocommerce_product_carousel_elementor_457e817a .owl-nav .owl-next.disabled {\n   display: none;\n}\n\t#uc_woocommerce_product_carousel_elementor_457e817a_item1 .uc_regular_price:not(.uc_regular_price--single){\n      display:none\n    }\n\n\t#uc_woocommerce_product_carousel_elementor_457e817a_item2 .uc_regular_price:not(.uc_regular_price--single){\n      display:none\n    }\n\n\t#uc_woocommerce_product_carousel_elementor_457e817a_item3 .uc_regular_price:not(.uc_regular_price--single){\n      display:none\n    }\n\n\t#uc_woocommerce_product_carousel_elementor_457e817a_item4 .uc_regular_price:not(.uc_regular_price--single){\n      display:none\n    }\n\n\t#uc_woocommerce_product_carousel_elementor_457e817a_item5 .uc_regular_price:not(.uc_regular_price--single){\n      display:none\n    }\n\n\t#uc_woocommerce_product_carousel_elementor_457e817a_item6 .uc_regular_price:not(.uc_regular_price--single){\n      display:none\n    }\n\n\t#uc_woocommerce_product_carousel_elementor_457e817a_item7 .uc_regular_price:not(.uc_regular_price--single){\n      display:none\n    }\n\n\t#uc_woocommerce_product_carousel_elementor_457e817a_item8 .uc_regular_price:not(.uc_regular_price--single){\n      display:none\n    }\n\n\t#uc_woocommerce_product_carousel_elementor_457e817a_item9 .uc_regular_price:not(.uc_regular_price--single){\n      display:none\n    }\n\n\t#uc_woocommerce_product_carousel_elementor_457e817a_item10 .uc_regular_price:not(.uc_regular_price--single){\n      display:none\n    }\n\n\n\n<\/style>\n\n<div class=\"uc_overlay_image_carousel\">\n   <div class=\"uc_carousel owl-carousel owl-theme uc-items-wrapper   \" id=\"uc_woocommerce_product_carousel_elementor_457e817a\"  data-custom-sethtml=\"true\" >\n   \t\t\n\n\n \n\n\n\n\n\n\n\n\n\n\n\n<div class=\"uc_image_carousel_container_holder ue-woo-item ue-item\" id=\"uc_woocommerce_product_carousel_elementor_457e817a_item1\">\n  \n   \n      \n  <div class=\"uc_image_carousel_placeholder\">\n    \n        \n    <a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/ivgm5-8kw-p2g1-us\/\">      \n        <div class=\"uc_product_image\" >    \n              <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2026\/06\/IVGM58kW-P2G1-US_1-768x768.webp\"  src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2026\/06\/IVGM58kW-P2G1-US_1-768x768.webp\" alt=\"Ivgm5~8kw P2g1 Us 1\" width=\"768\" height=\"768\">\n                \n  <\/div>\n      \n              \n    <\/a>\n    \n                  \t\n      \t\n      <\/div>\n  <div class=\"uc_image_carousel_content\" >\n    <div class=\"uc_image_carousel_content_inside\">\n      \n              \n            \n            \n      <div class=\"uc_post_title uc-direction\"><a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/ivgm5-8kw-p2g1-us\/\">IVGM5~8kW-P2G1-US<\/a><\/div>      \n            \n            \n      \n      <div class=\"uc_prices\">\n\n        \n              \n      <\/div>\n          \n\n      <div class=\"uc_post_grid_style_one_button uc_buttons\">\n\n              \n                        \n      <\/div>    <\/div>\n        \n  <\/div>  \n  <\/div>\n\n\n\n \n\n\n\n\n\n\n\n\n\n\n\n<div class=\"uc_image_carousel_container_holder ue-woo-item ue-item\" id=\"uc_woocommerce_product_carousel_elementor_457e817a_item2\">\n  \n   \n      \n  <div class=\"uc_image_carousel_placeholder\">\n    \n        \n    <a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/ivgm125khp3g1\/\">      \n        <div class=\"uc_product_image\" >    \n              <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2026\/04\/IVGM125KHP3G1-1-768x768.png\"  src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2026\/04\/IVGM125KHP3G1-1-768x768.png\" alt=\"Ivgm125khp3g1 (1)\" width=\"768\" height=\"768\">\n                \n  <\/div>\n      \n              \n    <\/a>\n    \n                  \t\n      \t\n      <\/div>\n  <div class=\"uc_image_carousel_content\" >\n    <div class=\"uc_image_carousel_content_inside\">\n      \n              \n            \n            \n      <div class=\"uc_post_title uc-direction\"><a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/ivgm125khp3g1\/\">IVGM125KHP3G1<\/a><\/div>      \n            \n            \n      \n      <div class=\"uc_prices\">\n\n        \n              \n      <\/div>\n          \n\n      <div class=\"uc_post_grid_style_one_button uc_buttons\">\n\n              \n                        \n      <\/div>    <\/div>\n        \n  <\/div>  \n  <\/div>\n\n\n\n \n\n\n\n\n\n\n\n\n\n\n\n<div class=\"uc_image_carousel_container_holder ue-woo-item ue-item\" id=\"uc_woocommerce_product_carousel_elementor_457e817a_item3\">\n  \n   \n      \n  <div class=\"uc_image_carousel_placeholder\">\n    \n        \n    <a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/flh48314ug1\/\">      \n        <div class=\"uc_product_image\" >    \n              <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2026\/04\/FLH48314UG1-1-768x768.png\"  src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2026\/04\/FLH48314UG1-1-768x768.png\" alt=\"Flh48314ug1 (1)\" width=\"768\" height=\"768\">\n                \n  <\/div>\n      \n              \n    <\/a>\n    \n                  \t\n      \t\n      <\/div>\n  <div class=\"uc_image_carousel_content\" >\n    <div class=\"uc_image_carousel_content_inside\">\n      \n              \n            \n            \n      <div class=\"uc_post_title uc-direction\"><a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/flh48314ug1\/\">FLH48314UG1<\/a><\/div>      \n            \n            \n      \n      <div class=\"uc_prices\">\n\n        \n              \n      <\/div>\n          \n\n      <div class=\"uc_post_grid_style_one_button uc_buttons\">\n\n              \n                        \n      <\/div>    <\/div>\n        \n  <\/div>  \n  <\/div>\n\n\n\n \n\n\n\n\n\n\n\n\n\n\n\n<div class=\"uc_image_carousel_container_holder ue-woo-item ue-item\" id=\"uc_woocommerce_product_carousel_elementor_457e817a_item4\">\n  \n   \n      \n  <div class=\"uc_image_carousel_placeholder\">\n    \n        \n    <a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/flm500-125-261\/\">      \n        <div class=\"uc_product_image\" >    \n              <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2026\/04\/FLM500-125261-800px-4-768x768.png\"  src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2026\/04\/FLM500-125261-800px-4-768x768.png\" alt=\"Flm500 125&amp;261 800px (4)\" width=\"768\" height=\"768\">\n                \n  <\/div>\n      \n              \n    <\/a>\n    \n                  \t\n      \t\n      <\/div>\n  <div class=\"uc_image_carousel_content\" >\n    <div class=\"uc_image_carousel_content_inside\">\n      \n              \n            \n            \n      <div class=\"uc_post_title uc-direction\"><a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/flm500-125-261\/\">FLM500-125\/261<\/a><\/div>      \n            \n            \n      \n      <div class=\"uc_prices\">\n\n        \n              \n      <\/div>\n          \n\n      <div class=\"uc_post_grid_style_one_button uc_buttons\">\n\n              \n                        \n      <\/div>    <\/div>\n        \n  <\/div>  \n  <\/div>\n\n\n\n \n\n\n\n\n\n\n\n\n\n\n\n<div class=\"uc_image_carousel_container_holder ue-woo-item ue-item\" id=\"uc_woocommerce_product_carousel_elementor_457e817a_item5\">\n  \n   \n      \n  <div class=\"uc_image_carousel_placeholder\">\n    \n        \n    <a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/ivgm10klp3g1\/\">      \n        <div class=\"uc_product_image\" >    \n              <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2026\/02\/10k.443-768x768.png\"  src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2026\/02\/10k.443-768x768.png\" alt=\"10k.443\" width=\"768\" height=\"768\">\n                \n  <\/div>\n      \n              \n    <\/a>\n    \n                  \t\n      \t\n      <\/div>\n  <div class=\"uc_image_carousel_content\" >\n    <div class=\"uc_image_carousel_content_inside\">\n      \n              \n            \n            \n      <div class=\"uc_post_title uc-direction\"><a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/ivgm10klp3g1\/\">IVGM10KLP3G1<\/a><\/div>      \n            \n            \n      \n      <div class=\"uc_prices\">\n\n        \n              \n      <\/div>\n          \n\n      <div class=\"uc_post_grid_style_one_button uc_buttons\">\n\n              \n                        \n      <\/div>    <\/div>\n        \n  <\/div>  \n  <\/div>\n\n\n\n \n\n\n\n\n\n\n\n\n\n\n\n<div class=\"uc_image_carousel_container_holder ue-woo-item ue-item\" id=\"uc_woocommerce_product_carousel_elementor_457e817a_item6\">\n  \n   \n      \n  <div class=\"uc_image_carousel_placeholder\">\n    \n        \n    <a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/fla48460-eu\/\">      \n        <div class=\"uc_product_image\" >    \n              <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/FLA48460-EU.png\"  src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/FLA48460-EU.png\" alt=\"Fla48460 Eu\" width=\"600\" height=\"600\">\n                \n  <\/div>\n      \n              \n    <\/a>\n    \n                  \t\n      \t\n      <\/div>\n  <div class=\"uc_image_carousel_content\" >\n    <div class=\"uc_image_carousel_content_inside\">\n      \n              \n            \n            \n      <div class=\"uc_post_title uc-direction\"><a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/fla48460-eu\/\">FLA48460-EU<\/a><\/div>      \n            \n            \n      \n      <div class=\"uc_prices\">\n\n        \n              \n      <\/div>\n          \n\n      <div class=\"uc_post_grid_style_one_button uc_buttons\">\n\n              \n                        \n      <\/div>    <\/div>\n        \n  <\/div>  \n  <\/div>\n\n\n\n \n\n\n\n\n\n\n\n\n\n\n\n<div class=\"uc_image_carousel_container_holder ue-woo-item ue-item\" id=\"uc_woocommerce_product_carousel_elementor_457e817a_item7\">\n  \n   \n      \n  <div class=\"uc_image_carousel_placeholder\">\n    \n        \n    <a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/fla48280-eu\/\">      \n        <div class=\"uc_product_image\" >    \n              <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/FLA48300.1-768x768.png\"  src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/FLA48300.1-768x768.png\" alt=\"Fla48300.1\" width=\"768\" height=\"768\">\n                \n  <\/div>\n      \n              \n    <\/a>\n    \n                  \t\n      \t\n      <\/div>\n  <div class=\"uc_image_carousel_content\" >\n    <div class=\"uc_image_carousel_content_inside\">\n      \n              \n            \n            \n      <div class=\"uc_post_title uc-direction\"><a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/fla48280-eu\/\">FLA48280-EU<\/a><\/div>      \n            \n            \n      \n      <div class=\"uc_prices\">\n\n        \n              \n      <\/div>\n          \n\n      <div class=\"uc_post_grid_style_one_button uc_buttons\">\n\n              \n                        \n      <\/div>    <\/div>\n        \n  <\/div>  \n  <\/div>\n\n\n\n \n\n\n\n\n\n\n\n\n\n\n\n<div class=\"uc_image_carousel_container_holder ue-woo-item ue-item\" id=\"uc_woocommerce_product_carousel_elementor_457e817a_item8\">\n  \n   \n      \n  <div class=\"uc_image_carousel_placeholder\">\n    \n        \n    <a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/fla48171-eu\/\">      \n        <div class=\"uc_product_image\" >    \n              <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/FLA48200.121-768x432.png\"  src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/FLA48200.121-768x432.png\" alt=\"Fla48200.121\" width=\"768\" height=\"432\">\n                \n  <\/div>\n      \n              \n    <\/a>\n    \n                  \t\n      \t\n      <\/div>\n  <div class=\"uc_image_carousel_content\" >\n    <div class=\"uc_image_carousel_content_inside\">\n      \n              \n            \n            \n      <div class=\"uc_post_title uc-direction\"><a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/fla48171-eu\/\">FLA48171-EU<\/a><\/div>      \n            \n            \n      \n      <div class=\"uc_prices\">\n\n        \n              \n      <\/div>\n          \n\n      <div class=\"uc_post_grid_style_one_button uc_buttons\">\n\n              \n                        \n      <\/div>    <\/div>\n        \n  <\/div>  \n  <\/div>\n\n\n\n \n\n\n\n\n\n\n\n\n\n\n\n<div class=\"uc_image_carousel_container_holder ue-woo-item ue-item\" id=\"uc_woocommerce_product_carousel_elementor_457e817a_item9\">\n  \n   \n      \n  <div class=\"uc_image_carousel_placeholder\">\n    \n        \n    <a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/fla48100-eu\/\">      \n        <div class=\"uc_product_image\" >    \n              <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/FLA48100.116-768x432.png\"  src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/FLA48100.116-768x432.png\" alt=\"Fla48100.116\" width=\"768\" height=\"432\">\n                \n  <\/div>\n      \n              \n    <\/a>\n    \n                  \t\n      \t\n      <\/div>\n  <div class=\"uc_image_carousel_content\" >\n    <div class=\"uc_image_carousel_content_inside\">\n      \n              \n            \n            \n      <div class=\"uc_post_title uc-direction\"><a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/fla48100-eu\/\">FLA48100-EU<\/a><\/div>      \n            \n            \n      \n      <div class=\"uc_prices\">\n\n        \n              \n      <\/div>\n          \n\n      <div class=\"uc_post_grid_style_one_button uc_buttons\">\n\n              \n                        \n      <\/div>    <\/div>\n        \n  <\/div>  \n  <\/div>\n\n\n\n \n\n\n\n\n\n\n\n\n\n\n\n<div class=\"uc_image_carousel_container_holder ue-woo-item ue-item\" id=\"uc_woocommerce_product_carousel_elementor_457e817a_item10\">\n  \n   \n      \n  <div class=\"uc_image_carousel_placeholder\">\n    \n        \n    <a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/fla24460-eu\/\">      \n        <div class=\"uc_product_image\" >    \n              <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/FLA24460-EU-768x768.png\"  src=\"https:\/\/felicitysolar.ca\/wp-content\/uploads\/2025\/10\/FLA24460-EU-768x768.png\" alt=\"Fla24460 Eu\" width=\"768\" height=\"768\">\n                \n  <\/div>\n      \n              \n    <\/a>\n    \n                  \t\n      \t\n      <\/div>\n  <div class=\"uc_image_carousel_content\" >\n    <div class=\"uc_image_carousel_content_inside\">\n      \n              \n            \n            \n      <div class=\"uc_post_title uc-direction\"><a href=\"https:\/\/felicitysolar.ca\/fr\/produit\/fla24460-eu\/\">FLA24460-EU<\/a><\/div>      \n            \n            \n      \n      <div class=\"uc_prices\">\n\n        \n              \n      <\/div>\n          \n\n      <div class=\"uc_post_grid_style_one_button uc_buttons\">\n\n              \n                        \n      <\/div>    <\/div>\n        \n  <\/div>  \n  <\/div>\n\n   <\/div>\t\n<\/div>\n\n\n  <div id=\"uc_woocommerce_product_carousel_elementor_457e817a_empty_message\" class=\"ue-no-posts-found\"  style=\"display:none\" >No products found<\/div>\n\n\n<!-- end Woo Product Carousel -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e5064d7 e-flex e-con-boxed e-con e-parent\" data-id=\"5e5064d7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fc301ce elementor-widget elementor-widget-ucaddon_custom_cursor\" data-id=\"4fc301ce\" data-element_type=\"widget\" data-widget_type=\"ucaddon_custom_cursor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Custom Cursor -->\n\n<style>\/* widget: Custom Cursor *\/\n\n#uc_custom_cursor_elementor_4fc301ce{\n  min-height: 1px;\n}\n\n#uc_custom_cursor_elementor_4fc301ce .ue-message{\n  padding: 10px;\n  border: 1px solid grey;\n  background-color: lightgrey;\n  border-radius: 5px;\n  font-size: 12px;\n}\n\n\/* should be written without #uc_custom_cursor_elementor_4fc301ce *\/\n.uc-mscursor-hidden{\n  display:none !important;\n}\n\n\/* cursor 2: custom cursor *\/\n  #uc_custom_cursor_elementor_4fc301ce .ue_cursor {\n    pointer-events: none;\n    opacity:1;\n    transition: all 300ms ease;\n  }\n\n  #uc_custom_cursor_elementor_4fc301ce .ue_cursor.cursor-inactive {\n    opacity:0;\n  }\n\n  #uc_custom_cursor_elementor_4fc301ce .cursor__ball {\n    display:flex;\n    position: fixed;\n    top: 0;\n    left: 0;\n    z-index: 1000;\n    pointer-events:none;\n    transform: matrix(1, 0, 0, 1, -100, -100);\n  }\n\n  #uc_custom_cursor_elementor_4fc301ce .cursor__ball--small{\n    display:flex;\n    align-items:center;\n    justify-content:center;\n  }\n\n  #uc_custom_cursor_elementor_4fc301ce .cursor__ball--small-inner{\n    display:flex;\n    align-items:center;\n    justify-content:center;\n  }\n\n  \n  \n      #uc_custom_cursor_elementor_4fc301ce .cursor__ball--big{\n           }\n  \n  \n\n\/* attention grabber  *\/\n\/* end attention grabber *\/\n\/* end cursor 2: custom cursor *\/\n\n<\/style>\n\n<div id=\"uc_custom_cursor_elementor_4fc301ce\" class=\"ue_cursor-wrap\" data-cursor=\"cursor-2\">\n  \n    \n  \n      <div class=\"ue_cursor ue_cursor-item ue_cursor-item--2\">\n      <div class=\"cursor__ball cursor__ball--big \"><\/div>      <div class=\"cursor__ball cursor__ball--small\">\n        <div class=\"cursor__ball--small-inner ue-floating-chat-blink\">\n                                    \t<\/div>\n        <\/div>\n    <\/div>\n  <\/div>\n<!-- end Custom Cursor -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>P2 Series P2 -80W 80W (Mono) Built-in 400WH 8H strong sunlight charge time IP65 Ingress Protection Product Introduction 1.1 Integrated design and source, high capacity LiFePO4 lithium battery, high energy, and long life, light weights, green and environmental protection, do not produce any harmful substances. 1.2 LED chip with high light efficiency which can reach [&hellip;]<\/p>\n","protected":false},"featured_media":24944,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[65,70],"product_tag":[216,213,214,176,215],"class_list":["post-25008","product","type-product","status-publish","has-post-thumbnail","product_cat-solar-street-light","product_cat-p3-series","product_tag-80w","product_tag-8h-strong-sunlight-charge-time","product_tag-all-in-one","product_tag-ip65","product_tag-solar-street-light","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-gallery-with-no-image","ast-product-tabs-layout-horizontal","first","instock","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/felicitysolar.ca\/fr\/wp-json\/wp\/v2\/product\/25008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/felicitysolar.ca\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/felicitysolar.ca\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/felicitysolar.ca\/fr\/wp-json\/wp\/v2\/comments?post=25008"}],"version-history":[{"count":14,"href":"https:\/\/felicitysolar.ca\/fr\/wp-json\/wp\/v2\/product\/25008\/revisions"}],"predecessor-version":[{"id":27794,"href":"https:\/\/felicitysolar.ca\/fr\/wp-json\/wp\/v2\/product\/25008\/revisions\/27794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felicitysolar.ca\/fr\/wp-json\/wp\/v2\/media\/24944"}],"wp:attachment":[{"href":"https:\/\/felicitysolar.ca\/fr\/wp-json\/wp\/v2\/media?parent=25008"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/felicitysolar.ca\/fr\/wp-json\/wp\/v2\/product_brand?post=25008"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/felicitysolar.ca\/fr\/wp-json\/wp\/v2\/product_cat?post=25008"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/felicitysolar.ca\/fr\/wp-json\/wp\/v2\/product_tag?post=25008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}